{"id":3073,"date":"2025-02-14T16:55:38","date_gmt":"2025-02-14T15:55:38","guid":{"rendered":"https:\/\/www.carboflotta.com\/?p=3073"},"modified":"2025-02-20T17:11:02","modified_gmt":"2025-02-20T16:11:02","slug":"refe-strategie-di-sviluppo-sostenibile-presso-carbofin","status":"publish","type":"post","link":"https:\/\/www.carboflotta.com\/it\/refe-strategie-di-sviluppo-sostenibile-presso-carbofin\/","title":{"rendered":"Refe \u2013 Strategie di Sviluppo Sostenibile presso Carbofin"},"content":{"rendered":"<p>Cristiana Rogate, Presidente della societ\u00e0 Refe \u2013 Strategie di Sviluppo Sostenibile che ci affianca da tempo sulle tematiche della sostenibilit\u00e0 e rendicontazione, ha tenuto presso gli uffici del Gruppo Carboflotta il primo incontro di un workshop a pi\u00f9 puntate inserito all&#8217;interno di un ampio percorso di formazione, focalizzato sulle tematiche della sostenibilit\u00e0 ed indirizzato a tutto il personale amministrativo. <\/p>\n<p>La formazione rappresenta un ulteriore passo importante per continuare ad approfondire e consolidare la cultura aziendale relativamente alle tematiche ESG.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cristiana Rogate, Presidente della societ\u00e0 Refe \u2013 Strategie di Sviluppo Sostenibile che ci affianca da tempo sulle tematiche della sostenibilit\u00e0&#8230;<\/p>\n","protected":false},"author":3,"featured_media":3074,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"_links":{"self":[{"href":"https:\/\/www.carboflotta.com\/it\/wp-json\/wp\/v2\/posts\/3073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carboflotta.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carboflotta.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carboflotta.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carboflotta.com\/it\/wp-json\/wp\/v2\/comments?post=3073"}],"version-history":[{"count":3,"href":"https:\/\/www.carboflotta.com\/it\/wp-json\/wp\/v2\/posts\/3073\/revisions"}],"predecessor-version":[{"id":3081,"href":"https:\/\/www.carboflotta.com\/it\/wp-json\/wp\/v2\/posts\/3073\/revisions\/3081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carboflotta.com\/it\/wp-json\/wp\/v2\/media\/3074"}],"wp:attachment":[{"href":"https:\/\/www.carboflotta.com\/it\/wp-json\/wp\/v2\/media?parent=3073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carboflotta.com\/it\/wp-json\/wp\/v2\/categories?post=3073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carboflotta.com\/it\/wp-json\/wp\/v2\/tags?post=3073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}